{"id":1050,"date":"2025-12-15T15:40:00","date_gmt":"2025-12-15T14:40:00","guid":{"rendered":"https:\/\/opera-executive.fr\/?p=1050"},"modified":"2026-04-01T15:42:28","modified_gmt":"2026-04-01T13:42:28","slug":"le-wne-2025-debordait-denergie","status":"publish","type":"post","link":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/","title":{"rendered":"Le WNE 2025 d\u00e9bordait d&rsquo;\u00e9nergie!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Retour sur le WNE 2025 : un salon professionnel sous le signe de l\u2019\u00e9nergie et des opportunit\u00e9s internationales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contrairement \u00e0 l\u2019id\u00e9e re\u00e7ue, un salon professionnel peut \u00eatre bien plus qu\u2019une simple journ\u00e9e de travail. Le WNE 2025 en est la preuve : une \u00e9dition vibrante, o\u00f9 l\u2019innovation, l\u2019engagement et la passion pour le nucl\u00e9aire \u00e9taient au rendez-vous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons eu le plaisir d\u2019y retrouver clients, partenaires et candidats, et d\u2019assister \u00e0 la concr\u00e9tisation de projets majeurs pour des entreprises fran\u00e7aises, comme Everllence. Ces r\u00e9alisations t\u00e9moignent de la dynamique et de l\u2019excellence de notre secteur, ainsi que de son ouverture grandissante sur la sc\u00e8ne internationale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le secteur nucl\u00e9aire confirme son expansion mondiale, avec des perspectives prometteuses sur des march\u00e9s en d\u00e9veloppement, notamment au Canada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un grand merci \u00e0 tous les participants pour ces \u00e9changes enrichissants, vos id\u00e9es et votre enthousiasme. Ces moments rappellent \u00e0 quel point les relations humaines restent au c\u0153ur de notre industrie, et c\u2019est ce qui la rend si inspirante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Retour sur le WNE 2025 : un salon professionnel sous le signe de l\u2019\u00e9nergie et des opportunit\u00e9s internationales Contrairement \u00e0 l\u2019id\u00e9e re\u00e7ue, un salon professionnel peut \u00eatre bien plus qu\u2019une simple journ\u00e9e de travail. Le WNE 2025 en est la preuve : une \u00e9dition vibrante, o\u00f9 l\u2019innovation, l\u2019engagement et la passion pour le nucl\u00e9aire \u00e9taient [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126,129],"tags":[],"class_list":["post-1050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-linkedin-fr","category-opera-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le WNE 2025 d\u00e9bordait d&#039;\u00e9nergie! - Opera International<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le WNE 2025 d\u00e9bordait d&#039;\u00e9nergie! - Opera International\" \/>\n<meta property=\"og:description\" content=\"Retour sur le WNE 2025 : un salon professionnel sous le signe de l\u2019\u00e9nergie et des opportunit\u00e9s internationales Contrairement \u00e0 l\u2019id\u00e9e re\u00e7ue, un salon professionnel peut \u00eatre bien plus qu\u2019une simple journ\u00e9e de travail. Le WNE 2025 en est la preuve : une \u00e9dition vibrante, o\u00f9 l\u2019innovation, l\u2019engagement et la passion pour le nucl\u00e9aire \u00e9taient [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/\" \/>\n<meta property=\"og:site_name\" content=\"Opera International\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-15T14:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T13:42:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.opera-executive.fr\/wp-content\/uploads\/2025\/11\/1762954461155-e1784304325753.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1243\" \/>\n\t<meta property=\"og:image:height\" content=\"1097\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Op\u00e9ra\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Op\u00e9ra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/\"},\"author\":{\"name\":\"Op\u00e9ra\",\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/#\\\/schema\\\/person\\\/d6b2226f3386ae6ad71e63a3f545a210\"},\"headline\":\"Le WNE 2025 d\u00e9bordait d&rsquo;\u00e9nergie!\",\"datePublished\":\"2025-12-15T14:40:00+00:00\",\"dateModified\":\"2026-04-01T13:42:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/\"},\"wordCount\":184,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.opera-executive.fr\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1762954461155-e1784304325753.jpeg\",\"articleSection\":[\"Linkedin\",\"OPERA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/\",\"url\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/\",\"name\":\"Le WNE 2025 d\u00e9bordait d'\u00e9nergie! - Opera International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.opera-executive.fr\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1762954461155-e1784304325753.jpeg\",\"datePublished\":\"2025-12-15T14:40:00+00:00\",\"dateModified\":\"2026-04-01T13:42:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.opera-executive.fr\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1762954461155-e1784304325753.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.opera-executive.fr\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1762954461155-e1784304325753.jpeg\",\"width\":1243,\"height\":1097},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/2025\\\/12\\\/15\\\/le-wne-2025-debordait-denergie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/fr\\\/1557-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le WNE 2025 d\u00e9bordait d&rsquo;\u00e9nergie!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/#website\",\"url\":\"https:\\\/\\\/www.opera-executive.fr\\\/\",\"name\":\"Opera International\",\"description\":\"Your gateway\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.opera-executive.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/#organization\",\"name\":\"Opera International\",\"url\":\"https:\\\/\\\/www.opera-executive.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.opera-executive.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Logo-International-Vectoriel-1.png\",\"contentUrl\":\"https:\\\/\\\/www.opera-executive.fr\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Logo-International-Vectoriel-1.png\",\"width\":840,\"height\":227,\"caption\":\"Opera International\"},\"image\":{\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/operainternational\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.opera-executive.fr\\\/#\\\/schema\\\/person\\\/d6b2226f3386ae6ad71e63a3f545a210\",\"name\":\"Op\u00e9ra\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f107fe794eb670796978f6bf136853bc975a0394f77a86a124ea4375e39760?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f107fe794eb670796978f6bf136853bc975a0394f77a86a124ea4375e39760?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3f107fe794eb670796978f6bf136853bc975a0394f77a86a124ea4375e39760?s=96&d=mm&r=g\",\"caption\":\"Op\u00e9ra\"},\"sameAs\":[\"https:\\\/\\\/opera-executive.fr\"],\"url\":\"https:\\\/\\\/www.opera-executive.fr\\\/index.php\\\/author\\\/admin9162\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le WNE 2025 d\u00e9bordait d'\u00e9nergie! - Opera International","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/","og_locale":"fr_FR","og_type":"article","og_title":"Le WNE 2025 d\u00e9bordait d'\u00e9nergie! - Opera International","og_description":"Retour sur le WNE 2025 : un salon professionnel sous le signe de l\u2019\u00e9nergie et des opportunit\u00e9s internationales Contrairement \u00e0 l\u2019id\u00e9e re\u00e7ue, un salon professionnel peut \u00eatre bien plus qu\u2019une simple journ\u00e9e de travail. Le WNE 2025 en est la preuve : une \u00e9dition vibrante, o\u00f9 l\u2019innovation, l\u2019engagement et la passion pour le nucl\u00e9aire \u00e9taient [&hellip;]","og_url":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/","og_site_name":"Opera International","article_published_time":"2025-12-15T14:40:00+00:00","article_modified_time":"2026-04-01T13:42:28+00:00","og_image":[{"width":1243,"height":1097,"url":"https:\/\/www.opera-executive.fr\/wp-content\/uploads\/2025\/11\/1762954461155-e1784304325753.jpeg","type":"image\/jpeg"}],"author":"Op\u00e9ra","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Op\u00e9ra","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/#article","isPartOf":{"@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/"},"author":{"name":"Op\u00e9ra","@id":"https:\/\/www.opera-executive.fr\/#\/schema\/person\/d6b2226f3386ae6ad71e63a3f545a210"},"headline":"Le WNE 2025 d\u00e9bordait d&rsquo;\u00e9nergie!","datePublished":"2025-12-15T14:40:00+00:00","dateModified":"2026-04-01T13:42:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/"},"wordCount":184,"commentCount":0,"publisher":{"@id":"https:\/\/www.opera-executive.fr\/#organization"},"image":{"@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.opera-executive.fr\/wp-content\/uploads\/2025\/11\/1762954461155-e1784304325753.jpeg","articleSection":["Linkedin","OPERA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/","url":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/","name":"Le WNE 2025 d\u00e9bordait d'\u00e9nergie! - Opera International","isPartOf":{"@id":"https:\/\/www.opera-executive.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/#primaryimage"},"image":{"@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.opera-executive.fr\/wp-content\/uploads\/2025\/11\/1762954461155-e1784304325753.jpeg","datePublished":"2025-12-15T14:40:00+00:00","dateModified":"2026-04-01T13:42:28+00:00","breadcrumb":{"@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/#primaryimage","url":"https:\/\/www.opera-executive.fr\/wp-content\/uploads\/2025\/11\/1762954461155-e1784304325753.jpeg","contentUrl":"https:\/\/www.opera-executive.fr\/wp-content\/uploads\/2025\/11\/1762954461155-e1784304325753.jpeg","width":1243,"height":1097},{"@type":"BreadcrumbList","@id":"https:\/\/www.opera-executive.fr\/index.php\/fr\/2025\/12\/15\/le-wne-2025-debordait-denergie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.opera-executive.fr\/index.php\/fr\/1557-2\/"},{"@type":"ListItem","position":2,"name":"Le WNE 2025 d\u00e9bordait d&rsquo;\u00e9nergie!"}]},{"@type":"WebSite","@id":"https:\/\/www.opera-executive.fr\/#website","url":"https:\/\/www.opera-executive.fr\/","name":"Opera International","description":"Your gateway","publisher":{"@id":"https:\/\/www.opera-executive.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.opera-executive.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.opera-executive.fr\/#organization","name":"Opera International","url":"https:\/\/www.opera-executive.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.opera-executive.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.opera-executive.fr\/wp-content\/uploads\/2024\/10\/Logo-International-Vectoriel-1.png","contentUrl":"https:\/\/www.opera-executive.fr\/wp-content\/uploads\/2024\/10\/Logo-International-Vectoriel-1.png","width":840,"height":227,"caption":"Opera International"},"image":{"@id":"https:\/\/www.opera-executive.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/operainternational"]},{"@type":"Person","@id":"https:\/\/www.opera-executive.fr\/#\/schema\/person\/d6b2226f3386ae6ad71e63a3f545a210","name":"Op\u00e9ra","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e3f107fe794eb670796978f6bf136853bc975a0394f77a86a124ea4375e39760?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3f107fe794eb670796978f6bf136853bc975a0394f77a86a124ea4375e39760?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3f107fe794eb670796978f6bf136853bc975a0394f77a86a124ea4375e39760?s=96&d=mm&r=g","caption":"Op\u00e9ra"},"sameAs":["https:\/\/opera-executive.fr"],"url":"https:\/\/www.opera-executive.fr\/index.php\/author\/admin9162\/"}]}},"_links":{"self":[{"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/posts\/1050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1050"}],"version-history":[{"count":2,"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/posts\/1050\/revisions"}],"predecessor-version":[{"id":1052,"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/posts\/1050\/revisions\/1052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/media\/889"}],"wp:attachment":[{"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.opera-executive.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}